{"id":356,"date":"2022-07-21T14:48:53","date_gmt":"2022-07-21T13:48:53","guid":{"rendered":"http:\/\/www.xn--motdedieuexpliqu-qqb.com\/?page_id=356"},"modified":"2023-04-05T00:08:24","modified_gmt":"2023-04-04T23:08:24","slug":"lois-du-dimanche","status":"publish","type":"page","link":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/lois-du-dimanche\/","title":{"rendered":"Lois du Dimanche"},"content":{"rendered":"\n<figure class=\"wp-block-table has-medium-font-size\"><table><tbody><tr><td><\/td><\/tr><tr><td><\/td><\/tr><tr><td>Ils [les m\u00e9chants du monde] ont d\u00e9clar\u00e9 qu&#8217;ils avaient la V\u00c9RIT\u00c9, que des miracles \u00e9taient parmi eux, que des anges du ciel parlaient avec eux et marchaient avec eux, qu&#8217;une grande puissance, des signes et des prodiges \u00e9taient accomplis parmi eux, et que c&#8217;\u00e9tait le mill\u00e9naire temporel qu&#8217;ils attendaient depuis si longtemps.&nbsp;Le monde entier a \u00e9t\u00e9 converti et en harmonie avec la LOI DU DIMANCHE, et ce PETIT GENS FAIBLE s&#8217;est dress\u00e9 au m\u00e9pris des lois du pays et de la LOI DE DIEU, et a pr\u00e9tendu \u00eatre les seuls \u00e0 avoir raison sur la terre.&nbsp;{Lt6-1884}<\/td><\/tr><tr><td>Il ne suffira pas \u00e0 ceux qui travaillent parmi les gens de couleur de pr\u00eacher la V\u00c9RIT\u00c9 aussi hardiment et ouvertement qu&#8217;ils seraient libres de le faire ailleurs.&nbsp;M\u00eame le CHRIST a rev\u00eatu SES LE\u00c7ONS de FIGURES et de PARABOLES pour \u00e9viter l&#8217;opposition des Pharisiens.&nbsp;Quand les gens de couleur sentiront qu&#8217;ils ont la PAROLE DE DIEU en ce qui concerne la question du SABBAT, et la sanction de ceux qui leur ont apport\u00e9 la V\u00c9RIT\u00c9, certains impulsifs en profiteront pour d\u00e9fier les LOIS DU DIMANCHE, et par un m\u00e9pris pr\u00e9somptueux de leurs oppresseurs, ils s&#8217;attireront beaucoup de chagrin.&nbsp;Tr\u00e8s fid\u00e8lement, les gens de couleur doivent \u00eatre instruits d&#8217;\u00eatre comme le CHRIST, de souffrir patiemment les torts, afin qu&#8217;ils puissent aider leurs semblables \u00e0 voir la LUMI\u00c8RE de la V\u00c9RIT\u00c9.&nbsp;{SW 69.3 1882-1889}<\/td><\/tr><tr><td>Le TEST viendra s\u00fbrement.&nbsp;Il y a trente-six ans, on m&#8217;a montr\u00e9 que ce qui est en train de se passer se produirait, que l&#8217;observance d&#8217;une institution de la papaut\u00e9 serait IMPOS\u00c9E AU PEUPLE par une LOI DU DIMANCHE, tandis que le JOUR DE REPOS SANCTIFI\u00c9 de J\u00c9HOVAH serait PIED.&nbsp;{5T 137.1 1882-1889}<\/td><\/tr><tr><td>Le m\u00eame esprit magistral [esprit] qui a complot\u00e9 contre les fid\u00e8les dans les si\u00e8cles pass\u00e9s cherche toujours \u00e0 d\u00e9barrasser la terre de ceux qui CRAIGNENT DIEU et OB\u00c9ISSENT \u00c0 SA LOI.&nbsp;Satan EXCITE L&#8217;INDIGNATION contre l&#8217;HUMBLE MINORITE qui REFUSE CONSCIENTEMENT d&#8217;accepter les coutumes et traditions populaires.&nbsp;Des hommes de position et de r\u00e9putation se joindront aux sans-loi et aux vils pour prendre conseil contre le PEUPLE de DIEU.&nbsp;La richesse, le g\u00e9nie, l&#8217;\u00e9ducation s&#8217;uniront pour les couvrir de m\u00e9pris.&nbsp;Les dirigeants pers\u00e9cuteurs, les ministres et les membres d&#8217;\u00e9glise CONSPIRONTERONT CONTRE EUX.&nbsp;Avec la voix et la plume, par les vantardises, les menaces et le ridicule, ils CHERCHERONT A RENVERSER leur FOI.&nbsp;Par de fausses repr\u00e9sentations et des appels furieux, ils attiseront les passions du peuple.&nbsp;N&#8217;ayant pas de &#8220;Ainsi dit les \u00c9CRITURES&#8221; \u00e0 opposer aux AVOCATS du SABBAT BIBLIQUE,&nbsp;ils auront recours \u00e0 des M\u00c9THODES D&#8217;OPPRESSION pour combler le manque.&nbsp;Pour s&#8217;assurer popularit\u00e9 et patronage, les l\u00e9gislateurs c\u00e9deront \u00e0 la demande d&#8217;une LOI DU DIMANCHE.&nbsp;Ceux qui craignent DIEU ne peuvent accepter une institution qui viole un PRECEPTE du DECALOGUE.&nbsp;Sur ce champ de bataille vient le DERNIER GRAND CONFLIT de la controverse entre la V\u00c9RIT\u00c9 et l&#8217;erreur.&nbsp;Et nous ne sommes pas laiss\u00e9s dans le doute quant \u00e0 la question.&nbsp;Maintenant, comme aux jours de Mardoch\u00e9e, le Seigneur justifiera SA V\u00c9RIT\u00c9 et SON PEUPLE.&nbsp;{5T 450.2 1882-1889}&nbsp;comme aux jours de Mardoch\u00e9e, le Seigneur justifiera SA V\u00c9RIT\u00c9 et SON PEUPLE.&nbsp;{5T 450.2 1882-1889}&nbsp;comme aux jours de Mardoch\u00e9e, le Seigneur justifiera SA V\u00c9RIT\u00c9 et SON PEUPLE.&nbsp;{5T 450.2 1882-1889}<\/td><\/tr><tr><td>Il y en a beaucoup, m\u00eame parmi ceux qui sont engag\u00e9s dans ce mouvement pour SUNDAY ENFORCEMENT, qui sont aveugl\u00e9s aux r\u00e9sultats qui suivront cette action.&nbsp;Ils ne voient pas qu&#8217;ils frappent directement contre la libert\u00e9 religieuse.&nbsp;Nombreux sont ceux qui n&#8217;ont jamais compris les pr\u00e9tentions du SABBAT BIBLIQUE et le faux fondement sur lequel repose l&#8217;institution du dimanche.&nbsp;Tout mouvement en faveur de la l\u00e9gislation religieuse est en r\u00e9alit\u00e9 un acte de concession \u00e0 la papaut\u00e9, qui depuis tant de si\u00e8cles n&#8217;a cess\u00e9 de lutter contre la libert\u00e9 de conscience.&nbsp;L&#8217;observance du dimanche doit son existence en tant qu&#8217;institution dite chr\u00e9tienne au \u00ab myst\u00e8re de l&#8217;iniquit\u00e9 \u00bb ;&nbsp;et son application sera une reconnaissance virtuelle des principes qui sont la pierre angulaire m\u00eame du romanisme.&nbsp;Lorsque notre nation abjurera les principes de son gouvernement au point de promulguer une LOI DU DIMANCHE,&nbsp;LE PROTESTANTISME, dans cet acte, JOINDRA LA MAIN AU PAPE;&nbsp;ce ne sera rien d&#8217;autre que de donner vie \u00e0 la tyrannie qui guette depuis longtemps avec impatience l&#8217;occasion de retomber dans le despotisme actif.&nbsp;{5T 711.4 1882-1889}<\/td><\/tr><tr><td>En tant que peuple, nous n&#8217;avons pas accompli le travail que DIEU nous a confi\u00e9.&nbsp;Nous ne sommes PAS PR\u00caTS pour le probl\u00e8me auquel nous am\u00e8nera l&#8217;APPLICATION de la LOI DU DIMANCHE.&nbsp;Il est de notre devoir, alors que nous voyons les signes d&#8217;un p\u00e9ril imminent, de nous r\u00e9veiller \u00e0 l&#8217;action.&nbsp;Ne laissez personne s&#8217;asseoir dans une attente calme du mal, se r\u00e9confortant avec la conviction que ce travail doit continuer parce que la PROPH\u00c9TIE l&#8217;a pr\u00e9dit, et que le Seigneur ABRITERA SON PEUPLE.&nbsp;Nous ne faisons pas la VOLONTE de DIEU si nous nous asseyons dans la qui\u00e9tude, ne faisant rien pour pr\u00e9server la libert\u00e9 de conscience.&nbsp;UNE PRI\u00c8RE FERVENTE ET EFFICACE devrait monter au ciel afin que cette MALADIE puisse \u00eatre DIFF\u00c9R\u00c9E jusqu&#8217;\u00e0 ce que nous puissions ACCOMPLIR l&#8217;\u0152UVRE qui a \u00e9t\u00e9 si longtemps n\u00e9glig\u00e9e.&nbsp;Qu&#8217;il y ait la PRI\u00c8RE LA PLUS FERME, puis TRAVAILLONS en HARMONIE avec NOS PRI\u00c8RES.&nbsp;Il peut sembler que Satan triomphe et que la V\u00c9RIT\u00c9 est domin\u00e9e par le mensonge et l&#8217;erreur ;&nbsp;le PEUPLE sur lequel DIEU a \u00e9tendu SON BOUCLIER, et le pays qui a \u00e9t\u00e9 un asile pour les SERVITEURS de DIEU opprim\u00e9s et les d\u00e9fenseurs de SA V\u00c9RIT\u00c9, peuvent \u00eatre mis en danger.&nbsp;Mais DIEU voudrait que nous nous rappelions SES INTERVENTIONS avec SON PEUPLE dans le pass\u00e9 pour les sauver de leurs ennemis.&nbsp;Il a toujours choisi les extr\u00e9mit\u00e9s, quand il semblait qu&#8217;il n&#8217;y avait aucune chance de d\u00e9livrance des oeuvres de Satan, pour la manifestation de SA PUISSANCE.&nbsp;La n\u00e9cessit\u00e9 de l&#8217;homme est l&#8217;OPPORTUNIT\u00c9 DE DIEU.&nbsp;Il se peut qu&#8217;un r\u00e9pit soit encore accord\u00e9 au PEUPLE DE DIEU pour qu&#8217;il se r\u00e9veille et laisse briller sa lumi\u00e8re.&nbsp;Si la pr\u00e9sence de dix justes aurait sauv\u00e9 les villes m\u00e9chantes de la plaine, n&#8217;est-il pas possible que DIEU le fasse encore, en r\u00e9ponse aux PRI\u00c8RES de SON PEUPLE,&nbsp;tenir en \u00e9chec les actions de ceux qui annulent SA LOI ?&nbsp;Ne devrions-nous pas humilier grandement nos c\u0153urs devant DIEU, fuir vers le SI\u00c8GE DE MIS\u00c9RICORDE et le supplier de r\u00e9v\u00e9ler SON PUISSANT POUVOIR ?&nbsp;{5T 713.4 1882-1889}<\/td><\/tr><tr><td>Nous attendons depuis de nombreuses ann\u00e9es qu&#8217;une LOI DU DIMANCHE soit promulgu\u00e9e dans notre pays;&nbsp;et, maintenant que le mouvement est sur nous, nous demandons : Notre peuple fera-t-il son devoir en la mati\u00e8re ?&nbsp;Ne pouvons-nous pas aider \u00e0 \u00e9lever la norme et \u00e0 appeler au front ceux qui respectent leurs droits et privil\u00e8ges religieux ?&nbsp;Le temps approche \u00e0 grands pas o\u00f9 ceux qui choisissent d&#8217;OB\u00c9IR \u00e0 DIEU plut\u00f4t qu&#8217;\u00e0 l&#8217;homme seront amen\u00e9s \u00e0 SENTIR la MAIN de l&#8217;OPPRESSION.&nbsp;Allons-nous alors D\u00c9SHONORER DIEU en GARANTISSANT LE SILENCE alors que SES SAINTS COMMANDEMENTS SONT FAIT SOUS LES PIEDS&nbsp;?&nbsp;{5T 716.1 1882-1889}<\/td><\/tr><tr><td>J&#8217;ai \u00e9t\u00e9 tr\u00e8s charg\u00e9 en ce qui concerne les mouvements qui sont actuellement en cours pour l&#8217;APPLICATION de l&#8217;OBSERVATION DU DIMANCHE.&nbsp;Il m&#8217;a \u00e9t\u00e9 montr\u00e9 que Satan a travaill\u00e9 s\u00e9rieusement pour mener \u00e0 bien ses desseins de RESTREINDRE LA LIBERT\u00c9 RELIGIEUSE.&nbsp;Des plans d&#8217;importance s\u00e9rieuse pour le PEUPLE de DIEU avancent d&#8217;une mani\u00e8re sournoise parmi les eccl\u00e9siastiques de diverses d\u00e9nominations, et l&#8217;objet de cette man\u0153uvre secr\u00e8te est de gagner la faveur populaire pour l&#8217;APPLICATION de la SACR\u00c9IT\u00c9 DU DIMANCHE.&nbsp;Si le PEUPLE peut \u00eatre amen\u00e9 \u00e0 FAVORER une LOI DU DIMANCHE, alors le clerg\u00e9 a l&#8217;intention d&#8217;exercer son influence unie pour OBTENIR un AMENDEMENT RELIGIEUX \u00e0 la CONSTITUTION et OBLIGER la NATION \u00e0 GARDER LE DIMANCHE.&nbsp;{Ms18-1888}<\/td><\/tr><tr><td>Je n&#8217;ai jamais vu le moment o\u00f9 nous avions davantage besoin de la PUISSANCE de DIEU dans nos \u00e2mes.&nbsp;Il y a une crise \u00e0 port\u00e9e de main.&nbsp;A la place de la LOI, les DIX COMMANDEMENTS seront ins\u00e9r\u00e9s dans la LOI DU DIMANCHE.&nbsp;Cette crise s&#8217;abat sur nous.&nbsp;Cette nation qui a \u00e9t\u00e9 b\u00e9nie tant d&#8217;ann\u00e9es avec la libert\u00e9 et la prosp\u00e9rit\u00e9 ;&nbsp;cette nation qui a joui de la libert\u00e9 religieuse bien au-del\u00e0 de celle des autres nations jusqu&#8217;\u00e0 ce qu&#8217;elle soit devenue un asile pour les opprim\u00e9s ;&nbsp;cette nation \u00e0 qui DIEU a donn\u00e9 des avantages sur toute autre nation sur la face de la terre;&nbsp;cette nation que DIEU a honor\u00e9e et b\u00e9nie;&nbsp;que font les gens de cette nation?&nbsp;{Ms20-1888}<\/td><\/tr><tr><td>\u2026 Si notre nation abjurait les principes du protestantisme, pour donner un visage et une sanction \u00e0 la LOI DU DIMANCHE, ils se joindraient dans cet acte au PAPIER ;&nbsp;car ce ne sera rien d&#8217;autre que de donner vie \u00e0 la tyrannie qui attend avec impatience et guette son occasion de se jeter dans le despotisme actif.&nbsp;Et maintenant, comme ce mal est sur le point de se r\u00e9aliser, c&#8217;est l&#8217;AFFAIRE de TOUS LES CROYANTS dans la BIBLE de S&#8217;\u00c9VEILLER.&nbsp;{RH, 11 d\u00e9cembre 1888 par.&nbsp;4}<\/td><\/tr><tr><td>\u2026 Vous rendez-vous compte que la nuit viendra bient\u00f4t, quand PERSONNE NE PEUT TRAVAILLER ?&nbsp;Avez-vous cette intensit\u00e9 de z\u00e8le, cette pi\u00e9t\u00e9 et cette d\u00e9votion, qui vous permettront de VOUS TENIR lorsque l&#8217;OPPOSITION vous tombera dessus ?&nbsp;Si DIEU a jamais parl\u00e9 par moi, le temps viendra o\u00f9 NOUS SERONS AMEN\u00c9S DEVANT LES CONSEILS, et CHAQUE POSITION de V\u00c9RIT\u00c9 que nous tenons sera S\u00c9V\u00c8REMENT CRITIQUE.&nbsp;Le temps que nous laissons maintenant perdre devrait \u00eatre consacr\u00e9 \u00e0 la charge que DIEU nous a confi\u00e9e, de nous pr\u00e9parer \u00e0 la crise qui approche.&nbsp;BEAUCOUP DE TEMPS DEVRAIT \u00caTRE PASS\u00c9 EN PRIERE, afin que nos V\u00caTEMENTS de CARACT\u00c8RE puissent \u00eatre lav\u00e9s et rendus blancs dans le SANG de l&#8217;AGNEAU.&nbsp;{RH, 11 d\u00e9cembre 1888 par.&nbsp;17}<\/td><\/tr><tr><td>Un temps vient o\u00f9 la LOI DE DIEU doit, dans un sens particulier, \u00eatre ANNUL\u00c9E dans notre pays.&nbsp;Les DIRIGEANTS de notre NATION, par des PROPOSITIONS L\u00c9GISLATIVES, appliqueront la LOI DU DIMANCHE, et ainsi le PEUPLE DE DIEU sera mis en GRAND P\u00c9RIL.&nbsp;Lorsque notre nation, dans ses conseils l\u00e9gislatifs, promulguera des lois pour lier les consciences des hommes en ce qui concerne leurs privil\u00e8ges religieux, IMPOSANT L&#8217;OBSERVATION DU DIMANCHE et imposant un POUVOIR D&#8217;OPPRESSION \u00e0 l&#8217;encontre de ceux qui OBSERVENT LE SABBAT DU SEPTI\u00c8ME JOUR, la LOI DE DIEU , \u00e0 toutes fins utiles, \u00eatre ANNUL\u00c9 dans notre pays&nbsp;;&nbsp;et L&#8217;APOSTASIE NATIONALE SERA SUIVIE PAR LA RUINE NATIONALE.&nbsp;Nous voyons que ceux qui GARDER maintenant les COMMANDEMENTS de DIEU ont besoin de s&#8217;am\u00e9liorer, afin qu&#8217;ils puissent obtenir l&#8217;AIDE SP\u00c9CIALE que DIEU seul peut leur donner.&nbsp;Ils devraient TRAVAILLER PLUS FERMEMENT pour RETARDER le plus longtemps possible la CALAMITE MENACEE.&nbsp;Si,&nbsp;dans notre pays de libert\u00e9 vant\u00e9e, un gouvernement protestant devrait sacrifier tous les principes qui entrent dans sa Constitution et propager le mensonge et l&#8217;illusion papaux, nous pouvons bien plaider : \u00ab Il est temps pour toi, Seigneur, de travailler, car ils ont annul\u00e9 ta droit.&#8221;&nbsp;Certains peuvent penser que parce qu&#8217;il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 dans la proph\u00e9tie que notre nation restreindra la conscience des hommes, cela doit s\u00fbrement arriver ;&nbsp;et que si nous faisons un effort pour pr\u00e9server notre libert\u00e9, nous agirons en serviteurs infid\u00e8les, et tomberons ainsi sous la CONDAMNATION de DIEU.&nbsp;{RH, 18 d\u00e9cembre 1888 par.&nbsp;6}&nbsp;\u00bb Certains peuvent penser que parce qu&#8217;il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 dans la proph\u00e9tie que notre nation restreindra la conscience des hommes, cela doit s\u00fbrement arriver ;&nbsp;et que si nous faisons un effort pour pr\u00e9server notre libert\u00e9, nous agirons en serviteurs infid\u00e8les, et tomberons ainsi sous la CONDAMNATION de DIEU.&nbsp;{RH, 18 d\u00e9cembre 1888 par.&nbsp;6}&nbsp;\u00bb Certains peuvent penser que parce qu&#8217;il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 dans la proph\u00e9tie que notre nation restreindra la conscience des hommes, cela doit s\u00fbrement arriver ;&nbsp;et que si nous faisons un effort pour pr\u00e9server notre libert\u00e9, nous agirons en serviteurs infid\u00e8les, et tomberons ainsi sous la CONDAMNATION de DIEU.&nbsp;{RH, 18 d\u00e9cembre 1888 par.&nbsp;6}<\/td><\/tr><tr><td>Si la d\u00e9cision est prise que notre peuple NE TRAVAILLERA PAS le DIMANCHE et que nos fr\u00e8res des \u00c9tats du Sud appara\u00eetront pour s&#8217;harmoniser avec la LOI DU DIMANCHE, \u00e0 cause de l&#8217;oppression, combien de temps avant que le monde entier [notre peuple] soit dans des circonstances similaires comme ils sont dans le Sud ?&nbsp;La D\u00c9CISION doit \u00eatre UNIVERSELLE.&nbsp;S&#8217;il vient \u00e0 la lumi\u00e8re du jour, comme il le fera par degr\u00e9s, et qu&#8217;il y aura des concessions et des inclinaisons serviles devant un dieu idole par ceux qui pr\u00e9tendent \u00eatre des observateurs du sabbat, il y aura un abandon des principes jusqu&#8217;\u00e0 ce que tout soit perdu pour eux.&nbsp;{Ms6-1889}<\/td><\/tr><tr><td>Nous ne sommes PAS PR\u00caTS pour ce GRAND PROBL\u00c8ME auquel l&#8217;APPLICATION de la LOI DU DIMANCHE nous am\u00e8nera.&nbsp;Que les MEMBRES de nos \u00e9glises DEVENENT DES MISSIONNAIRES pour le MA\u00ceTRE ;&nbsp;qu&#8217;ils ne s&#8217;attardent pas dans l&#8217;aisance et l&#8217;indiff\u00e9rence ;&nbsp;mais qu&#8217;ils s&#8217;en aillent pour TRAVAILLER pour DIEU.&nbsp;Leurs muscles spirituels ont \u00e9t\u00e9 presque paralys\u00e9s par l&#8217;inaction.&nbsp;Sortez du camp, portant l&#8217;OPPROCHE pour le CHRIST et la V\u00c9RIT\u00c9.&nbsp;Travaillez aujourd&#8217;hui dans la vigne du Seigneur.&nbsp;Allez sur les routes et les haies, et incitez les gens \u00e0 rechercher la V\u00c9RIT\u00c9.&nbsp;Malheur \u00e0 tous ceux qui professent marcher dans la lumi\u00e8re, mais qui sont \u00e0 l&#8217;aise en Sion.&nbsp;Ils absorbent les RAYONS DONN\u00c9S PAR DIEU de JUSTICE, mais ne diffusent pas la lumi\u00e8re aux autres.&nbsp;La parabole du serviteur infid\u00e8le qui cachait l&#8217;argent de son Seigneur, les condamne, et ils sont class\u00e9s parmi ceux qui refusent d&#8217;\u00eatre les collaborateurs de J\u00c9SUS-CHRIST, soucieux \u00e9go\u00efstement de leur bien-\u00eatre,&nbsp;et laissant ceux pour qui CHRIST est mort, p\u00e9rir sans la CONNAISSANCE de la V\u00c9RIT\u00c9 que DIEU leur a gracieusement donn\u00e9e.&nbsp;Ceux qui ont \u00e9t\u00e9 les r\u00e9cepteurs de la lumi\u00e8re spirituelle peuvent devenir les r\u00e9ceptacles des t\u00e9n\u00e8bres, \u00e0 qui les PAROLES du CHRIST sont applicables : \u00ab Si donc la lumi\u00e8re qui est en toi est t\u00e9n\u00e8bres, combien grandes sont ces t\u00e9n\u00e8bres !&nbsp;{RH, 1er janvier 1889 par.&nbsp;18}<\/td><\/tr><tr><td>Le m\u00eame esprit d&#8217;opposition \u00e0 l&#8217;\u00e9gard de la LOI DU DIMANCHE laissera une marque aussi profonde ici qu&#8217;en Am\u00e9rique.&nbsp;&#8220;LA MAIN DE DIEU n&#8217;est pas raccourcie qu&#8217;elle ne peut pas sauver, SON OREILLE n&#8217;est pas lourde qu&#8217;elle ne peut pas entendre.&#8221;&nbsp;Mais qui est-ce qui a l&#8217;argent du Seigneur ?&nbsp;Tous les efforts que nous pouvons faire sont inutiles sans argent et sans travailleurs.&nbsp;Nous ne devons pas avoir les mains li\u00e9es.&nbsp;Il est si essentiel d&#8217;introduire le levain dans le repas, et Satan fait ses efforts surhumains pour garder le levain \u00e0 l&#8217;ext\u00e9rieur en gardant la porte ferm\u00e9e.&nbsp;Je ressens intens\u00e9ment ce sujet.&nbsp;Les avertissements et les bonnes nouvelles, les bonnes nouvelles d&#8217;une grande joie, de ce qui est V\u00c9RIT\u00c9 seront-ils proclam\u00e9s au peuple ?&nbsp;CHRIST, par la vertu de SON SANG qui purifie de tout p\u00e9ch\u00e9, les attire \u00e0 l&#8217;ob\u00e9issance, et personne n&#8217;est \u00e0 l&#8217;\u0153uvre dans ces lieux.&nbsp;{Lt59a-1893}<\/td><\/tr><tr><td>Nos fr\u00e8res Firth de Kellyville, qui ont \u00e9t\u00e9 ARR\u00caT\u00c9S pour avoir enfreint la LOI DU DIMANCHE, ont \u00e9t\u00e9 aujourd&#8217;hui CONDAMN\u00c9S par la COUR soit \u00e0 payer l&#8217;amende de cinq shillings, soit \u00e0 \u00eatre plac\u00e9s dans les stocks.&nbsp;Ils ont apport\u00e9 une vieille loi faite \u00e0 l&#8217;\u00e9poque de Charles II pour s&#8217;appliquer \u00e0 ce cas de rupture du dimanche.&nbsp;Nos fr\u00e8res ont refus\u00e9 de payer l&#8217;amende, et seront donc mis au cachot.&nbsp;Mais comme les gens se sont [si] bien comport\u00e9s en Nouvelle-Galles du Sud, ces instruments de torture sont tomb\u00e9s en d\u00e9su\u00e9tude, et il n&#8217;y a pas d&#8217;instruments tels que des stocks \u00e0 la disposition des procureurs.&nbsp;Les stocks devront \u00eatre faits pour l&#8217;occasion pour punir le crime odieux de travailler le premier jour de la semaine.&nbsp;{Lt79-1894}<\/td><\/tr><tr><td>Nous vivons des moments int\u00e9ressants pour tous en Australie.&nbsp;La PRESSION de la LOI DU DIMANCHE est venue et vient.&nbsp;Il a \u00e9t\u00e9 ORDONN\u00c9 que TOUS LES MAGASINS SERONT FERM\u00c9S le DIMANCHE, et cela est RIGIDEMENT APPLIQU\u00c9.&nbsp;Le gouvernement ESSAIE DE FAIRE RECONNA\u00ceTRE DIEU dans la CONSTITUTION.&nbsp;Notre peuple prend une position aussi vigoureuse que possible pour qu&#8217;elle ne le soit pas.&nbsp;Ils ont obtenu des noms pour une p\u00e9tition \u00e0 cet effet.&nbsp;On voit que ce dont on parlait depuis trente-cinq ans, cette loi qui exalte le dimanche et fait que les inventions humaines tiennent lieu de JOUR SAINT DE DIEU, s&#8217;accomplit.&nbsp;Il y a beaucoup d&#8217;excitation maintenant \u00e0 l&#8217;\u00e9gard de ces questions.&nbsp;{Lt28-1897}<\/td><\/tr><tr><td>Nous n&#8217;avons jamais dout\u00e9 que ce soit le bon endroit pour implanter notre \u00e9cole.&nbsp;J&#8217;essaie d&#8217;amener nos fr\u00e8res \u00e0 sortir des villes sur un lopin de terre et \u00e0 \u00eatre pr\u00eats \u00e0 cultiver leurs propres produits.&nbsp;C&#8217;est ce qu&#8217;ils devront faire.&nbsp;Les LOIS DU DIMANCHE ont \u00e9t\u00e9 PASS\u00c9ES, et aussi rigoureuses qu&#8217;un peuple ignorant les LOIS de DIEU peut les rendre.&nbsp;Nous devons \u00eatre pr\u00eats \u00e0 toute urgence.&nbsp;Les \u00e9glises acc\u00e9l\u00e8rent l&#8217;histoire.&nbsp;Nous devons \u00eatre PLUS SOUVENT au TABOURET DE LA MIS\u00c9RICORDE, PLAIDANT avec DIEU.&nbsp;MARCHEZ HUMBLEMENT avec DIEU, mais ne manifestez pas un esprit l\u00e2che mais un ESPRIT de DEPENDANCE envers DIEU comme quelqu&#8217;un qui CROIT et FAIT CONFIANCE en DIEU.&nbsp;Le Seigneur est notre CONFIANCE et la couronne de notre r\u00e9jouissance.&nbsp;Marchez dans la voie du Seigneur et vous marcherez en toute s\u00e9curit\u00e9.&nbsp;Je dois fermer, car ma t\u00eate ne fonctionnera pas.&nbsp;{Lt177-1897}<\/td><\/tr><tr><td>Il devrait y avoir tous les efforts pour atteindre la WCTU [Woman&#8217;s Christian Temperance Union].&nbsp;Il y a beaucoup d&#8217;\u00e2mes aim\u00e9es de DIEU qui peuvent \u00eatre atteintes si elles sont approch\u00e9es comme des s\u0153urs en CHRIST J\u00c9SUS, faisant ce qu&#8217;elles peuvent.&nbsp;Il n&#8217;est pas n\u00e9cessaire d&#8217;aborder la question du SABBAT, car cela fermerait la porte \u00e0 beaucoup de c\u0153urs ;&nbsp;mais approchez-vous d&#8217;eux, unissez-vous \u00e0 eux dans le travail partout o\u00f9 il est sage de le faire.&nbsp;Cela ouvrira des points de divergence par rapport \u00e0 la LOI DU DIMANCHE.&nbsp;Expliquez ensuite en lisant un simple \u00ab Ainsi dit le Seigneur \u00bb.&nbsp;Les yeux de beaucoup d&#8217;entre eux sont aveugl\u00e9s.&nbsp;Ils sont dans une D\u00c9CEPTION HONNETE.&nbsp;Ils ont BESOIN de LUMI\u00c8RE sur cette grande question.&nbsp;Le sujet des r\u00e9formes viendra naturellement, et diverses opinions s&#8217;\u00e9l\u00e8veront ;&nbsp;mais qu&#8217;ils comprennent que les adventistes du septi\u00e8me jour travailleront en relation avec eux autant que possible dans le bon travail qu&#8217;ils font,&nbsp;et ainsi leur donner l&#8217;occasion de se familiariser avec les gens observant le sabbat auxquels ils s&#8217;opposent, pour beaucoup d&#8217;entre eux.&nbsp;{Ms74-1898}<\/td><\/tr><tr><td>Ensuite, il y a d&#8217;autres choses sur lesquelles ils peuvent tracer la ligne, mais nous ne sommes pas pr\u00eats pour que la ligne soit trac\u00e9e ici en ce qui concerne la LOI DU DIMANCHE.&nbsp;Allez simplement au travail, chacun de vous, pour d\u00e9cevoir le diable et voir tout ce que vous pouvez faire, combien d&#8217;\u00e2mes vous pouvez amener dans la V\u00c9RIT\u00c9.&nbsp;{Ms163-1898}<\/td><\/tr><tr><td>Satan met son interpr\u00e9tation sur les \u00e9v\u00e9nements, et ils pensent, comme il le voudrait, que les calamit\u00e9s qui remplissent le pays sont le r\u00e9sultat de la rupture du dimanche.&nbsp;Pensant apaiser la COLERE de DIEU, ces hommes influents font des LOIS FIXANT L&#8217;OBSERVATION DU DIMANCHE.&nbsp;Ils pensent qu&#8217;en exaltant de plus en plus haut ce faux jour de repos, en obligeant l&#8217;ob\u00e9issance \u00e0 la LOI DU DIMANCHE, le faux sabbat, ils rendent service \u00e0 DIEU.&nbsp;Ceux qui HONORENT DIEU en observant le VRAI SABBAT sont consid\u00e9r\u00e9s comme D\u00c9LOYAUX \u00e0 DIEU, alors que ce sont vraiment ceux qui les consid\u00e8rent ainsi qui sont eux-m\u00eames d\u00e9loyaux, parce qu&#8217;ils PI\u00c9TONNENT sous les PIEDS le SABBAT ORIGIN\u00c9 en \u00c9DEN.&nbsp;{Ms85-1899}<\/td><\/tr><tr><td>Il sera impossible d&#8217;emp\u00eacher les patients de s&#8217;enqu\u00e9rir de notre foi.&nbsp;Il y a ceux qui ont FAIM et SOIF de V\u00c9RIT\u00c9, et ceux-l\u00e0 la trouveront.&nbsp;C&#8217;est pourquoi nous voulons que notre institution soit \u00e9tablie imm\u00e9diatement.&nbsp;Nous souhaitons qu&#8217;elle ait \u00e9t\u00e9 \u00e9tablie avant la L\u00c9GISLATION sur les LOIS DU DIMANCHE, car nous pensons que si elle l&#8217;avait \u00e9t\u00e9, beaucoup d&#8217;yeux se seraient ouverts, et beaucoup d&#8217;\u00e2mes auraient suivi le droit chemin.&nbsp;{Ms111-1899}<\/td><\/tr><tr><td>L&#8217;\u0153il proph\u00e9tique de Jean voit un groupe qui n&#8217;a pas la marque de la b\u00eate.&nbsp;En les voyant, il s&#8217;\u00e9crie : &#8220;Voici la PATIENCE des SAINTS : voici ceux qui GARDER les COMMANDEMENTS de DIEU, et la FOI de J\u00c9SUS.&#8221;&nbsp;Deux parties sont mises en \u00e9vidence : l&#8217;une GARANTISSANT les COMMANDEMENTS de DIEU, \u00e0 la diff\u00e9rence de celle qui enfreint SES COMMANDEMENTS, faisant respecter le sabbat du dimanche, et OBLIGEANT les gens \u00e0 se CONFORMER \u00e0 la LOI DU DIMANCHE.&nbsp;Par l&#8217;union avec les opposants au SABBAT du QUATRI\u00c8ME COMMANDEMENT &#8211; le SABBAT DU SEPTI\u00c8ME JOUR &#8211; les hommes recevront la MARQUE de la B\u00caTE.&nbsp;Et tous ceux qui ont cette MARQUE p\u00e9riront avec l&#8217;homme de p\u00e9ch\u00e9, qui annule la LOI DE DIEU.&nbsp;{Lt118-1900}<\/td><\/tr><tr><td>Beaucoup de ceux qui travaillent pour SUNDAY ENFORCEMENT n&#8217;ont jamais compris les revendications du SABBAT BIBLIQUE et le faux fondement sur lequel repose l&#8217;institution du dimanche.&nbsp;Et ils sont aveugl\u00e9s par les r\u00e9sultats de la L\u00c9GISLATION DU DIMANCHE.&nbsp;Ils ne voient pas que ce serait un coup port\u00e9 \u00e0 la libert\u00e9 religieuse.&nbsp;Mais tout mouvement en faveur de la l\u00e9gislation religieuse est en r\u00e9alit\u00e9 un acte de concession \u00e0 la papaut\u00e9, qui depuis tant de si\u00e8cles n&#8217;a cess\u00e9 de lutter contre la libert\u00e9 de conscience.&nbsp;Le dimanche doit son existence en tant qu&#8217;institution dite chr\u00e9tienne au \u00ab myst\u00e8re de l&#8217;iniquit\u00e9 \u00bb ;&nbsp;et son application sera une reconnaissance virtuelle des principes qui sont la pierre angulaire m\u00eame du romanisme.&nbsp;Quand notre nation abjurera tellement les principes de son gouvernement qu&#8217;elle PROCURERA UNE LOI DU DIMANCHE, le PROTESTANTISME dans cet acte JOINDRA LA MAIN avec la PAPACIT\u00c9 ;&nbsp;elle donnera vie \u00e0 la tyrannie qui guettait depuis longtemps avec impatience l&#8217;occasion de retomber dans le despotisme actif.&nbsp;{ST, 28 novembre 1900 par.&nbsp;2}<\/td><\/tr><tr><td>Je vais essayer de r\u00e9pondre \u00e0 votre question sur ce que vous devriez faire dans le cas o\u00f9 les LOIS DU DIMANCHE sont APPLICABLES.&nbsp;{Lt132-1902}<\/td><\/tr><tr><td>La lumi\u00e8re que le Seigneur m&#8217;a donn\u00e9e \u00e0 un moment o\u00f9 nous nous attendions \u00e0 une crise telle que celle dont vous semblez approcher \u00e9tait que, lorsque les gens ont \u00e9t\u00e9 pouss\u00e9s par une puissance d&#8217;en bas \u00e0 METTRE EN \u0152UVRE L&#8217;OBSERVATION DU DIMANCHE, les Adventistes du Septi\u00e8me Jour devaient montrer leur sagesse en S&#8217;ABSTENANT DU TRAVAIL ce jour-l\u00e0, en le consacrant \u00e0 l&#8217;EFFORT MISSIONNAIRE.&nbsp;{Lt132-1902}<\/td><\/tr><tr><td>Lorsque nous CONSACRONS LE DIMANCHE AU TRAVAIL MISSIONNAIRE, le fouet sera retir\u00e9 des mains des fanatiques arbitraires qui seraient bien contents d&#8217;humilier les Adventistes du Septi\u00e8me jour.&nbsp;Quand ils verront que nous nous employons le dimanche \u00e0 VISITER LE PEUPLE et \u00e0 lui OUVRIR les ECRITURES, ils sauront qu&#8217;il est inutile qu&#8217;ils essaient d&#8217;entraver notre travail en faisant des LOIS DU DIMANCHE.&nbsp;{Lt132-1902}<\/td><\/tr><tr><td>Lorsque les LOIS DU DIMANCHE ont \u00e9t\u00e9 appliqu\u00e9es en Australie, nos fr\u00e8res qui \u00e9taient li\u00e9s \u00e0 l&#8217;\u00e9cole sont venus me demander conseil.&nbsp;\u00ab S\u0153ur White, demand\u00e8rent-ils, que devons-nous faire ?&nbsp;Allons-nous travailler le dimanche comme auparavant ?&nbsp;J&#8217;ai r\u00e9pondu : \u00ab Le dimanche est le meilleur jour de la semaine pour faire l&#8217;\u0152UVRE MISSIONNAIRE.&nbsp;Que les enseignants et les \u00e9tudiants consacrent cette journ\u00e9e \u00e0 DIEU.&nbsp;Divisez le pays environnant en districts, affectez une compagnie \u00e0 chaque district, puis visitez les gens tous les dimanches.&nbsp;Faites un TRAVAIL M\u00c9DICAL MISSIONNAIRE.&nbsp;Un tel travail ne suscitera pas d&#8217;opposition, et personne ne peut vous poursuivre pour l&#8217;avoir fait dimanche.&nbsp;Nous ne devons rien faire qui puisse attirer sur nous le m\u00e9contentement des hommes avant de leur avoir donn\u00e9 le message d&#8217;avertissement.&nbsp;Nous avons un grand travail \u00e0 faire,&nbsp;et aussi longtemps que possible, nous devons \u00e9viter de susciter des oppositions qui nous g\u00eaneraient dans l&#8217;accomplissement de ce travail.&nbsp;N&#8217;est-ce pas une bonne politique, juge Arthur ?&nbsp;{Ms93-1902}<\/td><\/tr><tr><td>C&#8217;est le r\u00e8gne de l&#8217;ant\u00e9christ.&nbsp;LA LOI DE DIEU EST ANNULEE.&nbsp;Les ECRITURES sont ECHANGEES contre les traditions des hommes.&nbsp;Satan est devenu le ma\u00eetre du monde ;&nbsp;et entre ses mains la tentation est devenue une science.&nbsp;Il r\u00e8gne sur un vaste empire bien organis\u00e9.&nbsp;Le p\u00e9ch\u00e9 a stimul\u00e9 ses partisans dans une activit\u00e9 effrayante.&nbsp;Les hommes se sont associ\u00e9s pour perp\u00e9tuer le mal.&nbsp;La vente de boissons enivrantes, destructrices pour l&#8217;\u00e2me et le corps, est l\u00e9galis\u00e9e par les gouvernements chr\u00e9tiens.&nbsp;Et ceux qui autorisent la vente de ce qui fait des hommes des d\u00e9mons font les LOIS DU DIMANCHE, qu&#8217;ils donnent au monde sous le nom solennel de religion.&nbsp;LE PEUPLE DE DIEU doit LUI montrer sa FID\u00c9LIT\u00c9 en GARANTISSANT SAINT le JOUR de SON REPOS.&nbsp;Ils doivent travailler avec ferveur pour mettre en \u0153uvre des influences qui contrecarreront les efforts de Satan.&nbsp;La LUMI\u00c8RE de la V\u00c9RIT\u00c9 doit \u00eatre r\u00e9pandue sur la terre.&nbsp;LA LOI DE DIEU doit \u00eatre PROCLAM\u00c9E.&nbsp;Un int\u00e9r\u00eat intense pour le MESSAGE de la V\u00c9RIT\u00c9 PR\u00c9SENTE doit \u00eatre \u00e9veill\u00e9.&nbsp;{Ms166-1902}<\/td><\/tr><tr><td>A l&#8217;\u00e9poque m\u00eame o\u00f9 nous vivons, le Seigneur a appel\u00e9 SON PEUPLE et lui a donn\u00e9 un message \u00e0 porter.&nbsp;Il les a appel\u00e9s \u00e0 EXPOSER la M\u00e9chancet\u00e9 de l&#8217;homme de p\u00e9ch\u00e9 qui a fait de la LOI DU DIMANCHE un pouvoir distinctif, qui a pens\u00e9 \u00e0 changer les temps et les lois, et \u00e0 opprimer le PEUPLE de DIEU qui se tient fermement pour L&#8217;HONORER en GARANTISSANT le SEUL VRAI SABBAT, le SABBAT de la CR\u00c9ATION, comme SAINT pour le SEIGNEUR.&nbsp;Il les a appel\u00e9s \u00e0 PORTER le SIGNE de DIEU, \u00e0 EXALTER le SEIGNEUR en GARANTISSANT SAINTE SA LOI;&nbsp;car c&#8217;est une TRANSCRIPTION de SON CARACTERE.&nbsp;Aucune partie de la LOI DE DIEU et de leur OBLIGATION CONTRACTUELLE de GARDER cette LOI SAINTE ne doit perdre ses pr\u00e9tentions contraignantes sur le monde entier.&nbsp;Ceux qui ont eu la lumi\u00e8re sur l&#8217;OBSERVATION de la LOI de J\u00c9HOVAH doivent SE TENIR FERMEMENT dans la FOI, et FAIRE BRILLER cette LUMI\u00c8RE dans des RAYONS CLAIRES ET DISTINCTS.&nbsp;{Ms139-1903}<\/td><\/tr><tr><td>La r\u00e9union de Middletown a \u00e9t\u00e9 profitable \u00e0 tous ceux qui avaient des oreilles pour entendre.&nbsp;Le SABBAT \u00e9tait un jour pr\u00e9cieux.&nbsp;La tente \u00e9tait bien remplie au service de l&#8217;apr\u00e8s-midi.&nbsp;Apr\u00e8s la r\u00e9union, un de nos ministres a dit : \u00ab Je crains qu&#8217;il n&#8217;y en ait pas autant demain ;&nbsp;car le Connecticut est l&#8217;\u00c9tat de la loi bleue, et les gens peuvent penser qu&#8217;ils enfreignent les LOIS DU DIMANCHE en assistant \u00e0 un service de camp-meeting au lieu d&#8217;aller dans leur propre \u00e9glise.&nbsp;J&#8217;ai dit : \u00ab Au lieu de parler d&#8217;incr\u00e9dulit\u00e9, disons au Seigneur \u00e0 quel point nous d\u00e9sirons que les gens entendent la V\u00c9RIT\u00c9.&nbsp;{Lt293-1904}<\/td><\/tr><tr><td>J&#8217;ai parl\u00e9 ici le SABBAT et le dimanche.&nbsp;Ils ont une excellente nouvelle tente, tr\u00e8s grande.&nbsp;Le camping est petit.&nbsp;Ce matin, deux de nos fr\u00e8res sont venus dans ma chambre et ont eu quelques mots de conversation avec moi, et ils ont exprim\u00e9 leurs craintes qu&#8217;aujourd&#8217;hui il n&#8217;y aurait que peu de sorties.&nbsp;Les LOIS DU DIMANCHE sont apr\u00e8s les anciennes lois bleues du Connecticut, et la remarque a \u00e9t\u00e9 faite qu&#8217;ils pourraient consid\u00e9rer comme un p\u00e9ch\u00e9 de venir \u00e0 notre r\u00e9union le dimanche.&nbsp;Mais tous furent surpris de voir les gens se presser de sorte qu&#8217;il fallait pr\u00e9voir des si\u00e8ges pour un grand nombre, puis un bon nombre se leva autour de la tente.&nbsp;J&#8217;ai vu devant moi la belle et grande tente neuve remplie de gens \u00e0 l&#8217;air intelligent, d&#8217;apparence de premi\u00e8re classe.&nbsp;J&#8217;ai parl\u00e9 de (1 Jean 3);&nbsp;Je portais fortement la question de la temp\u00e9rance, mais l&#8217;int\u00e9r\u00eat ne faiblit pas.&nbsp;Je suis tellement reconnaissant que le Seigneur m&#8217;ait fortifi\u00e9 par SA GRANDE PUISSANCE.&nbsp;{Lt380-1904}<\/td><\/tr><tr><td>Que ferons-nous, dit-on, quand la LOI DU DIMANCHE sera vot\u00e9e ?&nbsp;Pourquoi, dis-je, consacrer ce jour \u00e0 DIEU.&nbsp;Emmenez vos \u00e9tudiants et allez directement dans la brousse, comme ils l&#8217;appellent, allez directement dans les bois, et de maison en maison portez votre BIBLE, et l\u00e0 enseignez-leur le mode de vie.&nbsp;Agenouillez-vous et priez.&nbsp;Demandez-leur de venir \u00e0 J\u00c9SUS.&nbsp;Enseignez-leur le chemin.&nbsp;Alors dites-leur, comme l&#8217;a dit le CHRIST : \u00ab Venez \u00e0 moi, vous tous qui \u00eates fatigu\u00e9s et charg\u00e9s, et je vous donnerai du repos.&nbsp;\u00ab Maintenant, lui dis-je, vous les enseignez tous les dimanches ;&nbsp;enseignez-leur le SABBAT, bien s\u00fbr, mais chaque dimanche faites un don \u00e0 DIEU, et enseignez-leur comment ils peuvent trouver le chemin du ciel.&nbsp;{Ms153-1904}<\/td><\/tr><tr><td>En Australie, la nouvelle est arriv\u00e9e qu&#8217;une LOI DU DIMANCHE allait \u00eatre APPLIQU\u00c9E, et PERSONNE NE DEVRAIT TRAVAILLER.&nbsp;Eh bien, nous faisions tr\u00e8s attention de nous mettre du bon c\u00f4t\u00e9 des officiers, et quand nous avions notre verger, nous prenions quelques fruits, et nous les apportions \u00e0 ceux qui \u00e9taient dans la l\u00e9gislature, et nous les distribuions tout autour.&nbsp;Chaque fois que nous montions dans les voitures, nous disions : \u00ab Oh, quel festin nous avons eu avec ce que vous nous avez envoy\u00e9 !&nbsp;Alors notre peuple a dit: &#8220;Qu&#8217;allons-nous faire, si cela devait venir avec la LOI DU DIMANCHE et nous fermer notre travail?&#8221;&nbsp;&#8220;Eh bien, ce n&#8217;est pas encore l\u00e0&#8221;, avons-nous dit, &#8220;et tant qu&#8217;il n&#8217;est pas l\u00e0, pour l&#8217;amour de Dieu, allez travailler et faites tout ce que vous pouvez.&#8221;&nbsp;&#8220;Mais ces officiers, ils roulent ici tous les jours.&#8221;&nbsp;\u00ab Oui, dis-je, mais ils ne vous voient pas.&nbsp;Nous avons essay\u00e9 de nous lier d&#8217;amiti\u00e9 avec eux, et ils ne voient pas que vous travaillez,&nbsp;ils ne font aucun rapport.&nbsp;{Ms165-1904}<\/td><\/tr><tr><td>DIEU veut que nous TRAVAILLONS DUR pendant que nous sommes favoris\u00e9s.&nbsp;J&#8217;ai eu si peur qu&#8217;une certaine LOI DU DIMANCHE ferme notre travail afin que nous ne puissions pas faire tout ce que nous voulions faire ;&nbsp;J&#8217;ai ressenti tellement, que je ne pouvais pas dormir.&nbsp;Mais la B\u00c9N\u00c9DICTION de DIEU est venue sur moi une nuit quand j&#8217;ai senti que j&#8217;\u00e9tais dans cet \u00e9tat terrible.&nbsp;C&#8217;\u00e9tait comme si mon esprit avait \u00e9t\u00e9 mis \u00e0 rude \u00e9preuve.&nbsp;Pourquoi?&nbsp;Parce que j&#8217;\u00e9tais humain.&nbsp;Je me suis agenouill\u00e9 devant DIEU et j&#8217;ai dit: \u00abMaintenant, me voici, j&#8217;ai atteint la limite m\u00eame de la puissance de mon esprit.&nbsp;J&#8217;ai port\u00e9 ce fardeau jour et nuit.&nbsp;Pendant des semaines, je n&#8217;avais pas dormi apr\u00e8s midi.&nbsp;Et depuis quatre semaines je n&#8217;avais pas dormi avant midi.&nbsp;Maintenant, Seigneur, tu sais que je ne peux plus rien faire.&nbsp;Je jette mon \u00e2me impuissante sur toi ;&nbsp;gardez-moi mon cerveau.&nbsp;Je suis pr\u00eat \u00e0 souffrir dans n&#8217;importe quelle partie du corps, mais sauvez-moi mon cerveau.&nbsp;Je dois \u00e9crire.&nbsp;Je dois avoir mon esprit.&nbsp;{Ms165-1904}<\/td><\/tr><tr><td>Alors que nous travaillons de toutes nos forces, notre CONFIANCE doit \u00eatre en DIEU.&nbsp;T\u00f4t ou tard, les LOIS DU DIMANCHE seront adopt\u00e9es.&nbsp;Mais les SERVITEURS DE DIEU ont beaucoup \u00e0 faire pour AVERTIR LE PEUPLE.&nbsp;Ce travail a \u00e9t\u00e9 grandement retard\u00e9 par leur devoir d&#8217;attendre et de s&#8217;opposer aux desseins de Satan, qui s&#8217;est efforc\u00e9 de trouver une place dans notre travail.&nbsp;Nous avons des ann\u00e9es de retard.&nbsp;DIEU appelle SES OUVRIERS \u00e0 s&#8217;humilier devant LUI et \u00e0 RETIRER TOUS LES P\u00c9CH\u00c9S.&nbsp;IL les appelle \u00e0 s&#8217;en tenir fermement \u00e0 la parole : \u00ab Il est \u00e9crit \u00bb et \u00e0 \u00c9LOIGNER TOUTE INFID\u00c9LIT\u00c9.&nbsp;Nous devons nous humilier devant le Seigneur, et en m\u00eame temps nous devons \u00eatre aussi FERMES qu&#8217;un ROCHER au PRINCIPE.&nbsp;{Lt21-1905}<\/td><\/tr><tr><td>Le travail a \u00e9t\u00e9 commenc\u00e9 \u00e0 Washington, DC, pas trop t\u00f4t.&nbsp;Il aurait d\u00fb commencer il y a vingt-cinq ans.&nbsp;\u00c0 l&#8217;heure actuelle, il y a une FORTE AGITATION en faveur d&#8217;une LOI DU DIMANCHE pour le District de Columbia, et nos travailleurs travaillent de toutes leurs forces pour pr\u00e9senter les FAITS concernant le SABBAT BIBLIQUE et pour emp\u00eacher l&#8217;APPLICATION d&#8217;une LOI DU DIMANCHE.&nbsp;Les quotidiens publient des articles des deux c\u00f4t\u00e9s de la question.&nbsp;{Lt29-1905}<\/td><\/tr><tr><td>Et puis ils nous ont demand\u00e9 : Que ferez-vous maintenant lorsque la LOI DU DIMANCHE sera mise en ex\u00e9cution ?&nbsp;J&#8217;ai dit, j&#8217;ai tout trac\u00e9 dans ma t\u00eate, ce que je ferai et ce que je vous conseillerai de faire.&nbsp;Faites du dimanche une JOURN\u00c9E MISSIONNAIRE.&nbsp;Allez de maison en maison et portez les publications, pas les ordures du monde, mais PORTEZ LES PUBLICATIONS QUI LUI ENSEIGNERONT COMMENT OBTENIR LA VIE ETERNELLE.&nbsp;Vous leur donnez ainsi l&#8217;occasion de lire et de s&#8217;informer.&nbsp;{Ms193-1905}<\/td><\/tr><tr><td>Lorsque &#8216;Patriarches et Proph\u00e8tes&#8217; a \u00e9t\u00e9 publi\u00e9 pour la premi\u00e8re fois, il a \u00e9t\u00e9 n\u00e9glig\u00e9 pour un livre facile \u00e0 vendre et plus rentable pour les \u00e9diteurs.&nbsp;Beaucoup de nos gens ont \u00e9t\u00e9 aveugles \u00e0 l&#8217;importance des livres m\u00eames qui \u00e9taient les plus n\u00e9cessaires.&nbsp;Si le tact et l&#8217;habilet\u00e9 avaient alors \u00e9t\u00e9 d\u00e9montr\u00e9s dans la vente de ces livres, le mouvement SUNDAY LAW n&#8217;en serait pas l\u00e0 o\u00f9 il en est aujourd&#8217;hui.&nbsp;{RH, 16 f\u00e9vrier 1905 par.&nbsp;11}<\/td><\/tr><tr><td>Il est maintenant temps pour nous d&#8217;aller au front \u00e0 Washington.&nbsp;Alors que nous travaillons de toutes nos forces, NOTRE CONFIANCE DOIT \u00caTRE en DIEU.&nbsp;T\u00f4t ou tard, les LOIS DU DIMANCHE seront adopt\u00e9es.&nbsp;Mais les SERVITEURS DE DIEU ont beaucoup \u00e0 faire pour AVERTIR LE PEUPLE.&nbsp;Ce travail a \u00e9t\u00e9 grandement retard\u00e9 par leur devoir d&#8217;attendre et de s&#8217;opposer aux desseins de Satan, qui s&#8217;est efforc\u00e9 de trouver une place dans notre travail.&nbsp;Nous avons des ann\u00e9es de retard.&nbsp;{PH055 37.1 1905}<\/td><\/tr><tr><td>J&#8217;ai re\u00e7u de fr\u00e8re Colcord une lettre concernant son travail.&nbsp;J&#8217;esp\u00e8re que la trompette donnera un certain son en ce qui concerne ce mouvement LOI DU DIMANCHE.&nbsp;Je pense qu&#8217;il vaudrait mieux que dans nos journaux le sujet de la PERPETUITE de la LOI DE DIEU devienne une sp\u00e9cialit\u00e9.&nbsp;Ne devrait-il pas y avoir un journal ou une brochure publi\u00e9e pour remplacer la Sentinelle ?&nbsp;Je n&#8217;ai pas pu penser qu&#8217;il \u00e9tait sage de laisser tomber ce papier.&nbsp;C&#8217;\u00e9tait une voix qui parlait constamment pour d\u00e9fendre la LIBERT\u00c9 RELIGIEUSE.&nbsp;La V\u00c9RIT\u00c9 devrait \u00eatre PR\u00c9SENT\u00c9E dans des ARTICLES COURTS dans des LIGNES CLAIRES ET DISTINCTES, donnant des POINTS SP\u00c9CIAUX en ce qui concerne le SABBAT du SEIGNEUR et montrant que ceux qui \u00e9laborent des lois pour obliger l&#8217;observance du premier jour de la semaine sont d\u00e9loyaux envers le Seigneur des cieux, qui pla\u00e7a SA SAINTET\u00c9 au SEPTI\u00c8ME JOUR.&nbsp;Faisons-nous tout notre possible pour EXALTER la LOI de J\u00c9HOVAH ?&nbsp;{Lt58-1906}<\/td><\/tr><tr><td>Nous devrions maintenant faire de notre mieux pour vaincre cette LOI DU DIMANCHE.&nbsp;La meilleure fa\u00e7on d&#8217;y parvenir sera d&#8217;\u00e9lever la LOI DE DIEU et de la faire ressortir dans toute sa SACR\u00c9IT\u00c9.&nbsp;Cela doit \u00eatre fait si la V\u00c9RIT\u00c9 triomphe.&nbsp;{Lt58-1906}<\/td><\/tr><tr><td>Si nos \u00e9glises avaient tenu compte des PAROLES du MESSAGER DU SEIGNEUR, donn\u00e9es par la plume et la voix, si elles avaient pris leur position de VRAIS CROYANTS, nous aurions vu un rassemblement des plus merveilleux, qui aurait convaincu le monde que nous avons la V\u00c9RIT\u00c9.&nbsp;La LOI DE DIEU aurait \u00e9t\u00e9 MAGNIFIQUE.&nbsp;Et la LOI DU DIMANCHE, que des hommes de premier plan essaient d&#8217;introduire, aurait pu avoir peu d&#8217;influence.&nbsp;Mais les obstacles au milieu de nous ont travaill\u00e9 \u00e0 l&#8217;encontre des BUTS de DIEU.&nbsp;Mon c\u0153ur est presque bris\u00e9 quand je pense \u00e0 ce que le Seigneur m&#8217;a ouvert concernant ce qui aurait pu \u00eatre, mais qui n&#8217;est pas.&nbsp;{Lt58-1906}<\/td><\/tr><tr><td>L&#8217;effort qui est fait pour faire passer la LOI DU DIMANCHE doit \u00eatre vigoureusement rencontr\u00e9 ;&nbsp;car nous ne sommes pas pr\u00eats pour cette question.&nbsp;La crise est \u00e0 nos portes et bient\u00f4t le dernier probl\u00e8me devra \u00eatre r\u00e9solu.&nbsp;Chaque talent d\u00e9tenu en confiance par le PEUPLE DE DIEU devrait maintenant \u00eatre employ\u00e9 pour D\u00c9FENDRE la V\u00c9RIT\u00c9 telle qu&#8217;elle est en J\u00c9SUS, pour la faire se tenir devant le monde en lignes claires.&nbsp;{Lt72-1906}<\/td><\/tr><tr><td>Nous approchons de la fin de l&#8217;histoire de cette terre.&nbsp;Il y a des choses qui vont bouger tr\u00e8s rapidement maintenant.&nbsp;Des efforts d\u00e9termin\u00e9s sont faits pour mettre la LOI DU DIMANCHE en vigueur, et nous n&#8217;avons pas devant nous une perspective tr\u00e8s flatteuse.&nbsp;En tant que peuple, nous devons maintenant \u00eatre pr\u00e9par\u00e9s dans toutes nos \u00e9glises \u00e0 la crise.&nbsp;{Lt372-1906}<\/td><\/tr><tr><td>Nous arrivons maintenant \u00e0 l&#8217;endroit o\u00f9 il y aura des LOIS DU DIMANCHE \u00e0 respecter.&nbsp;Le TEST arrive rapidement sur les peuples du monde.&nbsp;Nous avons un excellent travail \u00e0 faire.&nbsp;Toute la force, le talent et la capacit\u00e9 de nos travailleurs ne doivent pas \u00eatre d\u00e9pens\u00e9s dans la conduite de restaurants ou dans la manipulation d&#8217;aliments naturels.&nbsp;Le SEIGNEUR J\u00c9SUS n&#8217;a pas fait la lumi\u00e8re sur les aliments de sant\u00e9 afin que les hommes puissent pr\u00e9tendre \u00eatre propri\u00e9taires des re\u00e7us de ces aliments.&nbsp;Ceux qui savent fabriquer ces aliments doivent donner l&#8217;impression que c&#8217;est le Seigneur qui est le donateur de tout notre bien.&nbsp;Les aliments di\u00e9t\u00e9tiques ne doivent pas devenir un moyen de sp\u00e9culation pour les gourmands et les \u00e9go\u00efstes.&nbsp;Ils doivent \u00eatre consid\u00e9r\u00e9s comme un moyen d&#8217;aider les pauvres et non comme un moyen d&#8217;enrichir quelques partis.&nbsp;Ce n&#8217;est pas le dessein du Seigneur ni SON PLAN que les aliments sains soient si chers que les pauvres ne peuvent pas se permettre de les utiliser.&nbsp;J&#8217;ai beaucoup \u00e0 dire sur ce sujet, mais je n&#8217;ai pas le temps maintenant d&#8217;\u00e9crire plus que peu de choses.&nbsp;{Lt372-1906}<\/td><\/tr><tr><td>Je m&#8217;attends \u00e0 voir un travail pointu \u00e0 l&#8217;avenir.&nbsp;Des tests serr\u00e9s et \u00e9prouvants arrivent.&nbsp;Je lance un appel urgent au PEUPLE DU SEIGNEUR pour qu&#8217;il apporte SES BIENS dans le tr\u00e9sor afin que notre travail puisse s&#8217;\u00e9largir et augmenter, atteignant un haut degr\u00e9 de sanctification.&nbsp;Je demande que des contributions lib\u00e9rales soient faites dans tous les pays, afin que la V\u00c9RIT\u00c9 puisse \u00eatre plac\u00e9e devant le peuple.&nbsp;Si, il y a des ann\u00e9es, nous avions \u00e9t\u00e9 plus z\u00e9l\u00e9s, nous aurions devanc\u00e9 l&#8217;ennemi en r\u00e9f\u00e9rence aux LOIS DU DIMANCHE.&nbsp;Dans chaque pays, un travail devrait \u00eatre fait semblable au travail que fait fr\u00e8re Simpson, mais ce travail n\u00e9cessitera des moyens.&nbsp;Nous DEVONS PRIER, fr\u00e8res et s\u0153urs.&nbsp;Nous devons travailler sans rel\u00e2che contre l&#8217;ennemi.&nbsp;Nous devons EXPLIQUER les MOTS de V\u00c9RIT\u00c9.&nbsp;La BIBLE explique la BIBLE, et moins de mots d&#8217;hommes et plus de MOTS de l&#8217;\u00c9CRITURE auront une influence dix fois plus grande.&nbsp;Nous avons besoin maintenant,&nbsp;en tant que peuple, la SANCTIFICATION du SAINT-ESPRIT.&nbsp;Nous devons MARCHER HUMBLEMENT avec DIEU.&nbsp;{Lt372-1906}<\/td><\/tr><tr><td>La V\u00c9RIT\u00c9 D&#8217;\u00c9PREUVE qui doit venir aux gens dans ces derniers jours doit \u00eatre pr\u00e9sent\u00e9e en LIGNES CLAIRES ET DROITES.&nbsp;Les hommes qui pr\u00e9conisent une LOI DU DIMANCHE ne respectent pas la PAROLE de J\u00c9HOVAH.&nbsp;Il dit : \u00ab En v\u00e9rit\u00e9, vous GARDEREZ MES SABBATS ;&nbsp;car c&#8217;est un SIGNE entre MOI et VOUS \u00e0 travers vos g\u00e9n\u00e9rations.&nbsp;{Lt72-1907}<\/td><\/tr><tr><td>Lorsque WC White m&#8217;a quitt\u00e9 le vendredi suivant, pour assister \u00e0 des r\u00e9unions \u00e0 Mexico et \u00e0 Nashville, j&#8217;ai craint d&#8217;\u00eatre \u00e0 la veille d&#8217;une d\u00e9pression.&nbsp;Pourtant, je sentais qu&#8217;avant de quitter Loma Linda, je devais pr\u00e9senter aux \u00e9tudiants la lumi\u00e8re qui m&#8217;avait \u00e9t\u00e9 donn\u00e9e concernant notre devoir en tant que peuple de PR\u00caCHER la PAROLE du DIEU VIVANT.&nbsp;Dans la nuit, il m&#8217;a sembl\u00e9 entendre la VOIX de DIEU, disant&nbsp;: N&#8217;entrez pas en pol\u00e9mique avec ceux qui sont d\u00e9termin\u00e9s \u00e0 promulguer les LOIS DU DIMANCHE, mais lisez-leur la PAROLE de l&#8217;\u00c9ternel&nbsp;: {Lt408-1907}<\/td><\/tr><tr><td>Il m&#8217;est venu aux oreilles que dans plusieurs endroits importants de cette partie de l&#8217;\u00c9tat, et ailleurs, il y en a qui sont agit\u00e9s \u00e0 l&#8217;id\u00e9e de faire tout ce qu&#8217;ils peuvent pour promulguer et appliquer les LOIS DU DIMANCHE.&nbsp;Je souhaite apporter devant vous quelques choses que DIEU a dites dans SA PAROLE concernant la SACR\u00c9IT\u00c9 et les REVENDICATIONS OBLIGATOIRES du SABBAT DU SEPTI\u00c8ME JOUR, tel qu&#8217;INSTITU\u00c9 dans l&#8217;EDEN.&nbsp;{Ms131-1907}<\/td><\/tr><tr><td>Ce sont des principes que nous devrions garder devant les gens de nos jours.&nbsp;Si nous MARCHONS HUMBLEMENT avec DIEU, nous aurons du succ\u00e8s aupr\u00e8s des gens ;&nbsp;mais nous ne devons pas tarder trop longtemps, de peur que l&#8217;ennemi n&#8217;entre comme un d\u00e9luge contre nous.&nbsp;D\u00e9j\u00e0 les forces du mal sont \u00e0 l&#8217;\u0153uvre dans un effort pour faire promulguer une LOI DU DIMANCHE, qui apporterait BEAUCOUP DE DIFFICULT\u00c9S \u00e0 CERTAINES PERSONNES PIEUSES.&nbsp;{Ms131-1907}<\/td><\/tr><tr><td>Nous devons faire face \u00e0 ce probl\u00e8me, en PR\u00caCHANT la PAROLE du DIEU VIVANT.&nbsp;La PAROLE est rapide et puissante, et plus tranchante que n&#8217;importe quelle \u00e9p\u00e9e \u00e0 deux tranchants.&nbsp;Alors que nous pr\u00e9sentons la V\u00c9RIT\u00c9 DU SABBAT directement \u00e0 partir de la PAROLE de DIEU, en la retra\u00e7ant de la CR\u00c9ATION \u00e0 la NOUVELLE TERRE, le T\u00c9MOIGNAGE du DIEU VIVANT, tel qu&#8217;enregistr\u00e9 dans SA PAROLE, aura un effet puissant sur ceux qui entendent.&nbsp;Notre force pour r\u00e9soudre le probl\u00e8me de la loi du dimanche se trouve dans le fait d&#8217;attirer l&#8217;attention du peuple sur un simple \u00ab Ainsi dit le Seigneur \u00bb.&nbsp;{Ms131-1907}<\/td><\/tr><tr><td>Puis ils sont venus et ont dit : Les officiers sont pass\u00e9s par l\u00e0.&nbsp;Voici la LOI DU DIMANCHE et les officiers ont fait le tour pour voir ce qu&#8217;ils pouvaient voir.&nbsp;J&#8217;ai dit, Dis-leur de ne pas avoir peur.&nbsp;Je connais bien ces officiers.&nbsp;Je les connais, et ce sont des hommes sens\u00e9s, et ils ne vous tra\u00eeneront jamais devant les tribunaux.&nbsp;Mais s&#8217;ils le font, dis-je, vous avez un rem\u00e8de ;&nbsp;qu&#8217;est-ce que c&#8217;est?&nbsp;Prenez votre BIBLE et allez dans la brousse, comme ils appellent les bois, l\u00e0 o\u00f9 se trouvent les colonies, puis instruisez-les.&nbsp;Et ils sont partis;&nbsp;la plupart de chaque jour de repos qu&#8217;ils avaient, ils allaient dans les bois, et ils trouvaient une compagnie, et ils leur enseignaient le soir, et ils travaillaient.&nbsp;Et nous en avons eu un certain nombre qui sont sortis dans la V\u00c9RIT\u00c9 \u00e0 partir de cet enseignement m\u00eame.&nbsp;{Ms185-1907}<\/td><\/tr><tr><td>D\u00e9fier les LOIS DU DIMANCHE ne fera que renforcer dans leur pers\u00e9cution les fanatiques religieux qui cherchent \u00e0 les faire respecter.&nbsp;Ne leur donnez aucune occasion de vous traiter de contrevenants.&nbsp;S&#8217;il leur est laiss\u00e9 de brider des hommes qui ne craignent ni DIEU ni l&#8217;homme, la bride perdra bient\u00f4t sa nouveaut\u00e9 pour eux, et ils verront qu&#8217;il n&#8217;est ni coh\u00e9rent ni convenable pour eux d&#8217;\u00eatre stricts quant \u00e0 l&#8217;observance du dimanche.&nbsp;Continuez votre travail, avec vos BIBLES entre les mains, et l&#8217;ennemi verra qu&#8217;il a nui \u00e0 sa propre cause.&nbsp;On ne re\u00e7oit pas la MARQUE de la B\u00caTE parce qu&#8217;on montre qu&#8217;on r\u00e9alise la sagesse de garder la paix en s&#8217;abstenant d&#8217;un travail qui offense, en faisant en m\u00eame temps un travail de la plus haute importance.&nbsp;{RP, 3 d\u00e9cembre 1907 par.&nbsp;4}<\/td><\/tr><tr><td>Le travail qui doit \u00eatre fait pour le Sud doit \u00eatre fait rapidement.&nbsp;Bient\u00f4t l&#8217;ennemi travaillera plus ouvertement pour l&#8217;adoption des LOIS DU DIMANCHE, et alors NOTRE TRAVAIL DEVRA SE FAIRE SOUS DE GRANDES DIFFICULT\u00c9S.&nbsp;Que les ouvriers soient envoy\u00e9s dans le champ sud.&nbsp;C&#8217;est une partie importante de la vigne du Seigneur.&nbsp;Dans certaines grandes villes, on trouve des repr\u00e9sentants de toutes les nationalit\u00e9s.&nbsp;Quand ceux-ci seront CONVERTIS \u00e0 la V\u00c9RIT\u00c9, ils travailleront pour leur propre peuple, et ainsi le travail s&#8217;\u00e9largira continuellement.&nbsp;{Lt170-1908}<\/td><\/tr><tr><td>Ici, la PAROLE DE DIEU sp\u00e9cifie clairement le jour qui doit \u00eatre GARDE SAINT, le SEPTI\u00c8ME JOUR ;&nbsp;et pourtant nous voyons un travail men\u00e9 par des ministres, des m\u00e9decins, des avocats et des dirigeants qui aboutira \u00e0 l&#8217;application d&#8217;une LOI DU DIMANCHE.&nbsp;DIEU ne punira-t-il pas cette r\u00e9bellion ?&nbsp;Il punira s\u00fbrement, comme cela est repr\u00e9sent\u00e9 dans les mots que j&#8217;ai copi\u00e9s.&nbsp;{Lt254-1908}<\/td><\/tr><tr><td>Satan, Lucifer, d\u00e9ploiera ses efforts d\u00e9termin\u00e9s pour introduire et exalter une LOI DU DIMANCHE, qu&#8217;il cherchera de toutes les mani\u00e8res possibles \u00e0 \u00e9tablir.&nbsp;Il ne suffit pas d&#8217;\u00e9viter les dangers flagrants et les mouvements p\u00e9rilleux et incoh\u00e9rents.&nbsp;NOUS DEVONS \u00caTRE \u00c9VEILL\u00c9S.&nbsp;Lucifer, qui est entr\u00e9 en grande partie dans le mercantilisme, travaillera dans cette voie, car il a perdu sa position dans les cours c\u00e9lestes et a \u00e9t\u00e9 expuls\u00e9 vers notre monde.&nbsp;\u00c0 moins que chaque \u00e9glise re\u00e7oive l&#8217;avertissement et soit sur ses gardes, nous mettrons nos \u00e2mes en p\u00e9ril en nous \u00e9loignant de la SIMPLICIT\u00c9 de la VRAIE PI\u00c9T\u00c9.&nbsp;D&#8217;innombrables d\u00e9ceptions seront rev\u00eatues des v\u00eatements de la v\u00e9rit\u00e9 ;&nbsp;\u00e0 moins que nos ministres, nos m\u00e9decins et nos enseignants de toutes les branches ne se r\u00e9veillent, ils seront vaincus.&nbsp;Certains qui ne regardent pas seront pris au pi\u00e8ge de la conception de Satan.&nbsp;Dans le jardin de Geths\u00e9man\u00e9, les disciples ont \u00e9t\u00e9 avertis,&nbsp;&#8220;Veillez et priez, de peur que vous n&#8217;entriez en tentation.&#8221;&nbsp;Il est maintenant temps pour nous de veiller jusqu&#8217;\u00e0 la pri\u00e8re, de peur que nous ne soyons surpris en train de dormir alors que nous serions bien \u00e9veill\u00e9s.&nbsp;{Ms133-1908}<\/td><\/tr><tr><td>Il y a du travail pour tous \u00e0 faire afin que les V\u00c9RIT\u00c9S SIMPLES de la PAROLE DE DIEU puissent \u00eatre connues.&nbsp;Les MOTS de l&#8217;\u00c9CRITURE doivent \u00eatre imprim\u00e9s et publi\u00e9s tels qu&#8217;ils sont lus.&nbsp;Ce serait bien si le DIX-NEUVI\u00c8ME et la PLUS GRANDE PARTIE DES CHAPITRES VINGTI\u00c8ME DE L&#8217;EXODE, avec les VERSETS DOUZE \u00c0 DIX-HUIT DU CHAPITRE TRENTE-UNI\u00c8ME, \u00e9taient imprim\u00e9s tels quels.&nbsp;Rassemblez ces V\u00c9RIT\u00c9S dans des PETITS LIVRES et des BROCHURES, et laissez la PAROLE DE DIEU parler aux gens.&nbsp;Quand on pr\u00eache un discours concernant la loi qui va droit au but, si vous avez un moyen de le faire, mettez-le dans un tract imprim\u00e9.&nbsp;Ensuite, lorsque ceux qui plaident pour les LOIS DU DIMANCHE vous rencontreront, placez ces tracts dans leurs mains.&nbsp;Dites-leur que vous n&#8217;avez pas de discussion sur la question du dimanche ;&nbsp;car vous avez un &#8220;Ainsi dit le Seigneur&#8221; clair pour l&#8217;OBSERVATION du SEPTI\u00c8ME JOUR.&nbsp;{RH, 26 mars 1908 par.&nbsp;9}<\/td><\/tr><tr><td>Je suis charg\u00e9 de dire \u00e0 notre peuple dans toutes les villes du Sud : Que tout se fasse sous la direction du Seigneur.&nbsp;Les travaux touchent \u00e0 leur fin.&nbsp;Nous sommes plus pr\u00e8s de la fin que lorsque nous avons cru pour la premi\u00e8re fois.&nbsp;Satan fait de son mieux pour bloquer la voie \u00e0 la progression du message.&nbsp;Il d\u00e9ploie des efforts pour provoquer la PROC\u00c9DATION d&#8217;une LOI DU DIMANCHE, qui se traduira par l&#8217;esclavage dans le champ sud et fermera la porte \u00e0 l&#8217;observance du VRAI SABBAT que DIEU a donn\u00e9 aux hommes pour les GARDER SAINTS.&nbsp;La LOI qu&#8217;IL est descendu du ciel au Mont Sina\u00ef pour proclamer doit \u00eatre OBSERV\u00c9E PAR TOUS ceux qui s&#8217;identifieraient avec le PEUPLE de DIEU.&nbsp;Veuillez lire et relire le quatri\u00e8me chapitre du Deut\u00e9ronome.&nbsp;Le chapitre entier devrait \u00eatre \u00e9tudi\u00e9 attentivement par ceux qui seraient compt\u00e9s parmi LE PEUPLE GARANT DE L&#8217;ALLIANCE DE DIEU.&nbsp;{Lt6-1909}<\/td><\/tr><tr><td>Vous devriez vous sentir r\u00e9solument responsable du fonctionnement de la ville de New York.&nbsp;Les hommes des maisons de commerce de New York et d&#8217;autres grandes villes, aussi certainement que les pa\u00efens des pays \u00e9trangers, doivent \u00eatre touch\u00e9s par le message.&nbsp;L&#8217;ennemi se r\u00e9jouirait de voir la grande, sauvant la V\u00c9RIT\u00c9 pour cette fois confin\u00e9e \u00e0 quelques endroits.&nbsp;Il n&#8217;est pas inactif.&nbsp;Il inculque dans l&#8217;esprit des hommes ses th\u00e9ories trompeuses pour aveugler leurs yeux et confondre leur compr\u00e9hension, afin que la V\u00c9RIT\u00c9 salvatrice ne puisse pas \u00eatre port\u00e9e \u00e0 leur connaissance.&nbsp;Bient\u00f4t, les LOIS DU DIMANCHE seront APPLIQU\u00c9ES, et les hommes occupant des postes de confiance seront AIGRIS contre la PETITE POIGN\u00c9E DE GENS GARANTISSANT LES COMMANDEMENTS DE DIEU.&nbsp;Satan semble avoir \u00e9t\u00e9 autoris\u00e9 \u00e0 gagner de nombreux points d&#8217;avantage.&nbsp;Mais le Seigneur am\u00e8nera des hommes de compr\u00e9hension des diff\u00e9rentes \u00e9glises pour lutter contre l&#8217;application d&#8217;une loi selon laquelle le premier jour de la semaine sera honor\u00e9 comme un jour o\u00f9 AUCUNE AFFAIRE ne sera TRANSACT\u00c9E.&nbsp;{Lt143-1909} &amp; {Lt168-1909}<\/td><\/tr><tr><td>Au cours de la nuit pass\u00e9e, j&#8217;ai sembl\u00e9 \u00e9num\u00e9rer dans mon esprit les preuves que nous avons pour justifier la foi que nous d\u00e9tenons.&nbsp;On voit que les s\u00e9ducteurs sont de pire en pire.&nbsp;Nous voyons le monde travailler au point d&#8217;\u00e9tablir par la loi un faux sabbat et d&#8217;en faire un test pour tous.&nbsp;Cette question sera bient\u00f4t devant nous.&nbsp;LE SABBAT DE DIEU sera PIED et un faux sabbat sera exalt\u00e9.&nbsp;Dans cette LOI DU DIMANCHE, il y a POSSIBILIT\u00c9 DE GRANDES SOUFFRANCES pour ceux qui OBSERVENT LE SEPTI\u00c8ME JOUR.&nbsp;L&#8217;ex\u00e9cution des plans de Satan apportera la PERS\u00c9CUTION au PEUPLE de DIEU.&nbsp;Mais les FID\u00c8LES SERVITEURS de DIEU n&#8217;ont pas \u00e0 craindre l&#8217;issue du conflit.&nbsp;S&#8217;ils SUIVRONT LE MOD\u00c8LE \u00e9tabli pour eux dans la VIE de CHRIST, s&#8217;ils seront FID\u00c8LES aux EXIGENCES de DIEU, leur r\u00e9compense sera la VIE \u00c9TERNELLE, une VIE qui mesure avec la VIE de DIEU.&nbsp;{Ms11-1909}<\/td><\/tr><tr><td>Le dimanche peut \u00eatre utilis\u00e9 pour poursuivre diverses lignes de travail qui accompliront beaucoup pour le Seigneur.&nbsp;Ce jour-l\u00e0, des R\u00c9UNIONS EN PLEIN AIR et des R\u00c9UNIONS DE COTTAGE peuvent avoir lieu.&nbsp;Le TRAVAIL DE MAISON \u00c0 MAISON peut \u00eatre fait.&nbsp;Ceux qui \u00e9crivent peuvent consacrer cette journ\u00e9e \u00e0 \u00c9CRIRE LEURS ARTICLES.&nbsp;Chaque fois que cela est possible, que les SERVICES RELIGIEUX aient lieu le dimanche.&nbsp;Rendez ces r\u00e9unions intens\u00e9ment int\u00e9ressantes.&nbsp;CHANTER DE V\u00c9RITABLES HYMNES DE REVEIL, et PARLER avec PUISSANCE et ASSURANCE de l&#8217;AMOUR DU SAUVEUR.&nbsp;PARLEZ de la TEMP\u00c9RANCE et de la VRAIE EXP\u00c9RIENCE RELIGIEUSE.&nbsp;Vous apprendrez ainsi beaucoup sur la fa\u00e7on de travailler, et toucherez de nombreuses \u00e2mes.&nbsp;{9T 233.1 1909}<\/td><\/tr><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Ils [les m\u00e9chants du monde] ont d\u00e9clar\u00e9 qu&#8217;ils avaient la V\u00c9RIT\u00c9, que des miracles \u00e9taient parmi eux, que des anges du ciel parlaient avec eux et marchaient avec eux, qu&#8217;une grande puissance, des signes et des prodiges \u00e9taient accomplis parmi eux, et que c&#8217;\u00e9tait le mill\u00e9naire temporel qu&#8217;ils attendaient depuis si longtemps.&nbsp;Le monde entier [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-356","page","type-page","status-publish","hentry","odd"],"_links":{"self":[{"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/pages\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":3,"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/pages\/356\/revisions"}],"predecessor-version":[{"id":1084,"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/pages\/356\/revisions\/1084"}],"wp:attachment":[{"href":"https:\/\/www.xn--motdedieuexpliqu-qqb.com\/index.php\/wp-json\/wp\/v2\/media?parent=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}